{"id":14538,"date":"2013-05-14T21:07:36","date_gmt":"2013-05-14T22:07:36","guid":{"rendered":"http:\/\/www.clubotaku.org\/niji\/?p=14538"},"modified":"2013-05-14T21:07:36","modified_gmt":"2013-05-14T22:07:36","slug":"guia-a-saude-no-japao","status":"publish","type":"post","link":"https:\/\/www.clubotaku.org\/niji\/socie\/guia-a-saude-no-japao\/","title":{"rendered":"[Guia] : A Sa\u00fade no Jap\u00e3o"},"content":{"rendered":"<p>O Jap\u00e3o possui um sistema de sa\u00fade muito desenvolvido e funcional, embora muito diferente do Ocidental. Um estrangeiro poder\u00e1 receber tratamento em hospitais privados mas ir\u00e1 pagar um valor obsceno no final. Al\u00e9m disso, nem todos os hospitais, mesmo os privados, t\u00eam pessoal fluente em ingl\u00eas. A \u00fanica maneira de ser atendido num hospital p\u00fablico, ter direito a int\u00e9rprete (ali\u00e1s, \u00e9 um call center de int\u00e9rpretes), receber tratamento de emerg\u00eancia, adquirir \u201creceita\u201d para medicamento ou ser enviado de volta a Portugal se ocorrer um acidente grave \u00e9 fazer um seguro de sa\u00fade para viagem. <\/p>\n<p>Este seguro \u00e9 muito diferente do seguro autom\u00e1tico que se faz quando se compra um voo com o cart\u00e3o de cr\u00e9dito ou quando se faz um \u201cseguro de viagem\u201d, isto porque n\u00e3o \u00e9 sobre a bagagem e o transporte mas sim sobre os cuidados de sa\u00fade.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/2408.jpg\" alt=\"2\" width=\"640\" height=\"290\" class=\"aligncenter size-full wp-image-14539\" srcset=\"https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/2408.jpg 640w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/2408-300x135.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Os seguros de sa\u00fade para viagem cobrem per\u00edodos at\u00e9 tr\u00eas meses e os pre\u00e7os (para tr\u00eas meses) variam entre 300 e mais de 1000 euros. Para que este seja reconhecido pelo sistema hospitalar do Jap\u00e3o tem de ser um seguro de sa\u00fade realizado por uma seguradora internacional, por exemplo uma empresa como a Allianz, ou ent\u00e3o por uma empresa de seguros e servi\u00e7os de sa\u00fade que seja americana-japonesa, francesa-japonesa, etc. N\u00e3o existe nenhuma seguradora portuguesa-japonesa para isto, por isso uma das hip\u00f3teses \u00e9 fazer por uma seguradora que tenha servi\u00e7os on-line (ex.: worldnomads). Alguns estrangeiros a viver no Jap\u00e3o h\u00e1 v\u00e1rios anos j\u00e1 criaram sistemas de cuidados de sa\u00fade que s\u00e3o reconhecidos pelos hospitais p\u00fablicos japoneses e funcionam como seguros de sa\u00fade, como a \u201chealthone\u201d ou a \u201cviva vida\u201d por exemplo, mas os servi\u00e7os devem ser adquiridos antes da entrada no pa\u00eds (por internet).<\/p>\n<p>Para ser atendido numa farm\u00e1cia n\u00e3o \u00e9 preciso seguro de sa\u00fade, no entanto s\u00f3 poder\u00e3o vender determinados medicamentos, o equivalente ao nosso sistema de \u201cvenda livre\u201d (sem receita do m\u00e9dico). Estes medicamentos n\u00e3o s\u00e3o quimicamente sintetizados, ou seja, s\u00e3o extractos naturais de plantas e minerais. O seu efeito \u00e9 mais lento embora tamb\u00e9m sejam eficientes. <\/p>\n<p>Outras coisas como a aplica\u00e7\u00e3o de compressas sobre feridas, pensos t\u00e9rmicos para les\u00f5es musculares e mesmo medicamentos para baixar a febre, isso \u00e9 de venda livre. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/3365.jpg\" alt=\"3\" width=\"640\" height=\"290\" class=\"aligncenter size-full wp-image-14540\" srcset=\"https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/3365.jpg 640w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/3365-300x135.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><strong>Conselhos pr\u00e1ticos e curtos sobre sa\u00fade<\/strong><\/p>\n<p>N\u00e3o s\u00e3o necess\u00e1rias vacinas adicionais ao Plano Nacional de Vacina\u00e7\u00e3o portugu\u00eas. Se uma pessoa viajar depois de Setembro deve tomar a vacina da gripe antes de ir. Se for para o sul do Jap\u00e3o, mais exactamente zonas rurais ou as ilhas a sul de Kyushu, deve tomar por as precau\u00e7\u00f5es geralmente recomendadas para climas tropicais h\u00famidos. Nesta zona a doen\u00e7a mais perigosa \u00e9 \u201cJapanese B encephalitis\u201d (mortal, sem cura) que \u00e9 transmitida pela picada de um mosquito, pelo que o uso de redes e spray repelente \u00e9 obrigat\u00f3rio. <\/p>\n<p>Deve ter-se em considera\u00e7\u00e3o que no Jap\u00e3o n\u00e3o \u00e9 aceit\u00e1vel mostrar cicatrizes. Se uma pessoa tiver uma cicatriz exposta (n\u00e3o coberta com roupa) deve usar SEMPRE um penso a cobrir essa \u00e1rea de pele. Se for na cara deve tentar cobrir com o cabelo ou maquilhagem (mesmo homens). <\/p>\n<p>Feridas ou zonas de pele com borbulhas avermelhadas ou em erup\u00e7\u00e3o tamb\u00e9m devem ser sempre cobertas com pensos discretos ou maquilhagem. Espirrar ou mesmo respirar quando se est\u00e1 constipado tamb\u00e9m deve ser isolado da vista (e ar) dos outros, nesse caso usa-se uma m\u00e1scara m\u00e9dica que existe \u00e1 venda em lojas de conveni\u00eancia e farm\u00e1cias por todo o Jap\u00e3o.<\/p>\n<p>Como isto \u00e9 sobre o Jap\u00e3o quero terminar com uma imagem para sorrir! O Jap\u00e3o \u00e9 um dos pa\u00edses mais inventivos no que toca a criar doces e guloseimas estranhas. \u201cPensos de chocolate de leite\u201d pareceu-me adequar-se a este tema.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/411.jpg\" alt=\"4\" width=\"640\" height=\"290\" class=\"aligncenter size-full wp-image-14541\" srcset=\"https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/411.jpg 640w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/411-300x135.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Claro que estes n\u00e3o s\u00e3o para por nas feridas\u2026mas quem \u00e9 que achou \u201cdivertido\u201d comer pensos?<\/p>\n<p>E por hoje \u00e9 tudo e j\u00e1 chega de conselhos sobre sa\u00fade, antes que algu\u00e9m fique doente&#8230; Se quiseres saber mais dicas fiquem atentos aos pr\u00f3ximos cap\u00edtulos, ou ent\u00e3o viajarem at\u00e9 ao ind\u00edce deste guia (<a href=\"http:\/\/www.clubotaku.org\/niji\/guia-de-sobrevivencia\/\" title=\"clicar aqui\">clicar aqui<\/a>). At\u00e9 \u00e0 Pr\u00f3xima!!!<\/p>\n<p><strong>Escrito por: In\u00eas Carvalho Matos<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Jap\u00e3o possui um sistema de sa\u00fade muito desenvolvido e funcional, embora muito diferente do Ocidental. Um estrangeiro poder\u00e1 receber tratamento em hospitais privados mas ir\u00e1 pagar um valor obsceno&nbsp;[ &hellip; ]<\/p>\n","protected":false},"author":2,"featured_media":14540,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1283,10,2773,7],"tags":[3135,3136],"_links":{"self":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts\/14538"}],"collection":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/comments?post=14538"}],"version-history":[{"count":0,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts\/14538\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/media\/14540"}],"wp:attachment":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/media?parent=14538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/categories?post=14538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/tags?post=14538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}