{"id":14586,"date":"2013-05-22T07:34:26","date_gmt":"2013-05-22T08:34:26","guid":{"rendered":"http:\/\/www.clubotaku.org\/niji\/?p=14586"},"modified":"2013-05-22T17:19:36","modified_gmt":"2013-05-22T18:19:36","slug":"guia-viajar-de-comboio","status":"publish","type":"post","link":"https:\/\/www.clubotaku.org\/niji\/socie\/guia-viajar-de-comboio\/","title":{"rendered":"[Guia] : Viajar de comboio"},"content":{"rendered":"<p>O Jap\u00e3o tem uma rede de transportes p\u00fablicos de sonho. A rede ferrovi\u00e1ria cobre praticamente todas as zonas, \u00e9 segura e pontual, e ainda por cima inventaram uma coisa maravilhosa chamada \u201cJapan Rail Pass\u201d. Para quem quer ver muita coisa e deslocar-se bastante no pa\u00eds esta \u00e9 sem d\u00favida a melhor op\u00e7\u00e3o.<\/p>\n<p>O Japan Rail Pass \u00e9 um passe de comboios de alta velocidade (shinkansen) e que tamb\u00e9m serve para alguns outros comboios regionais r\u00e1pidos (o equivalente ao nosso \u201calfa\u201d). Existem v\u00e1rias companhias ferrovi\u00e1rias no pa\u00eds mas a que tem mais cobertura \u00e9 a \u201cJapan Rail\u201d, para a qual este passe \u00e9 v\u00e1lido. S\u00f3 pode ser adquirido atrav\u00e9s do \u201cJapan Tourism Bureau\u201d e fora do Jap\u00e3o. Isto \u00e9 importante: n\u00e3o \u00e9 poss\u00edvel adquiri-lo no Jap\u00e3o.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/1551.jpg\" alt=\"1\" width=\"640\" height=\"290\" class=\"aligncenter size-full wp-image-14587\" srcset=\"https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/1551.jpg 640w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/1551-300x135.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>O Japan Rail Pass deve ser encomendado com anteced\u00eancia (at\u00e9 dois meses antes do in\u00edcio da viagem) para um dos escrit\u00f3rios do Japan Tourism Bureau na Europa, sendo que o mais perto de n\u00f3s \u00e9 o de Madrid. Depois de se pedir informa\u00e7\u00e3o atrav\u00e9s de um simples email, chega-nos a indica\u00e7\u00e3o de duas vers\u00f5es de passe e diferentes pre\u00e7os conforme a dura\u00e7\u00e3o (7 dias, 14 dias ou 21 dias). O passe s\u00f3 come\u00e7a a contar os dias a partir da primeira vez que \u00e9 usado mas a data a partir da qual pretendemos us\u00e1-lo j\u00e1 tem de vir escrita na \u201cExchange Order\u201d que compramos atrav\u00e9s do \u201cJapan Tourism Bureau\u201d. Por isso quando escolhemos o passe j\u00e1 temos de ter o plano da nossa viagem.<\/p>\n<p>O pre\u00e7o que vemos escrito pode fazer perder o f\u00f4lego, mas depois de uma pesquisa sobre quanto custam os bilhetes do shinkansen quando comprados individualmente e no Jap\u00e3o, fica rapidamente esclarecido que este passe poupa efectivamente muito dinheiro. Os japoneses que me viam usar este passe expressavam sempre, e com muita emotividade, como se sentiam injusti\u00e7ados que os estrangeiros pudessem beneficiar deste passe e eles tivessem que pagar mais do que o pre\u00e7o de um bilhete de avi\u00e3o pela mesma viagem.<\/p>\n<p>A aquisi\u00e7\u00e3o da \u201cExchange Order\u201d \u00e9 f\u00e1cil. Depois de escolhermos a modalidade e dura\u00e7\u00e3o do passe informam-nos do pre\u00e7o e da refer\u00eancia para transfer\u00eancia banc\u00e1ria internacional. Fazemos a transfer\u00eancia por internet ou multibanco e enviamos uma c\u00f3pia do comprovativo por email. Passadas algumas semanas recebemos a \u201cExchange Order\u201d em casa e guardamo-la para levar connosco. Assim que se chega, mesmo nos aeroportos, existe um gabinete para ir trocar esse documento pelo passe. Nesse momento v\u00e3o verificar o nosso passaporte e pedir assinatura, mas \u00e9 tudo muito tranquilo e com um atendimento muito simp\u00e1tico. Se estiver calor at\u00e9 s\u00e3o capazes de vos oferecer ch\u00e1 e ajudar com as malas!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/2411.jpg\" alt=\"2\" width=\"640\" height=\"290\" class=\"aligncenter size-full wp-image-14588\" srcset=\"https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/2411.jpg 640w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/2411-300x135.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>As duas modalidades do Japan Rail Pass distinguem-se basicamente pela op\u00e7\u00e3o \u201cgreen car\u201d, que na vers\u00e3o mais barata n\u00e3o existe. Este \u201cgreen car\u201d \u00e9 a carruagem ou conjunto de carruagens com marca\u00e7\u00e3o de lugar antecipada e com um pouco mais de luxo. Para quem anda de viagem n\u00e3o \u00e9 bom comprar esta vers\u00e3o com \u201cgreen car\u201d por dois motivos: \u00e9 mais caro, e teria de se fazer a reserva de lugar antes da compra do bilhete na esta\u00e7\u00e3o (atrav\u00e9s de telefonema ou internet).<\/p>\n<p>Muitos estrangeiros confundem isto do \u201cgreen car\u201d com \u201creserva\u201d mas n\u00e3o \u00e9 t\u00e3o simples. O passe sem a modalidade \u201cgreen car\u201d n\u00e3o significa que uma pessoa possa entrar no comboio e sentar-se onde quer. \u00c9 sempre necess\u00e1rio dirigir-se \u00e0 bilheteira, que tem uma fila exclusiva para os portadores deste passe, e comprar o bilhete.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/3368.jpg\" alt=\"3\" width=\"640\" height=\"290\" class=\"aligncenter size-full wp-image-14589\" srcset=\"https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/3368.jpg 640w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/3368-300x135.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>O bilhete tem o lugar marcado e a pessoa que entrega o bilhete explica onde se l\u00ea o n\u00famero do lugar. Nestas bilheteiras exclusivas para portadores do Japan Rail Pass falam bem ingl\u00eas e podemos aproveitar para lhes fazer perguntas sobre o itiner\u00e1rio. S\u00e3o muito prest\u00e1veis, e geralmente fazem pesquisa de percursos criando um documento impresso com a descri\u00e7\u00e3o da nossa viagem (no caso de ser necess\u00e1rio trocar em alguma esta\u00e7\u00e3o).<\/p>\n<p>Nos comboios de alta velocidade (shinkansen) e em alguns dos comboios regionais r\u00e1pidos mais associados a percursos tur\u00edsticos \u00e9 aceit\u00e1vel comer a bordo, e existem mesmo quiosques nas plataformas de embarque que vendem caixas de refei\u00e7\u00e3o (bento) e respectivos \u201cpauzinhos\u201d. No entanto nos outros comboios e em geral em todos os transportes p\u00fablicos n\u00e3o se pode comer nem beber nas carruagens.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/412.jpg\" alt=\"4\" width=\"640\" height=\"290\" class=\"aligncenter size-full wp-image-14590\" srcset=\"https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/412.jpg 640w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/412-300x135.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Para finalizar com bom humor aqui fica uma ideia japonesa: souvenir do shinkansen. Se gostou da experi\u00eancia porque n\u00e3o andar com o comboio cal\u00e7ado? Ou ent\u00e3o oferecer aos seus filhos!<\/p>\n<p>Chegamos ao fim da viagem&#8230; contamos brevemente voltar a viajar por este pa\u00eds que fascinante e que todos adoramos&#8230; Se quiseres saber mais dicas fiquem atentos aos pr\u00f3ximos cap\u00edtulos, ou ent\u00e3o viajarem at\u00e9 ao ind\u00edce deste guia (<a href=\"http:\/\/www.clubotaku.org\/niji\/guia-de-sobrevivencia\/\" title=\"clicar aqui\">clicar aqui<\/a>). At\u00e9 \u00e0 Pr\u00f3xima!!!<\/p>\n<p><strong>Escrito por: In\u00eas Carvalho Matos<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Jap\u00e3o tem uma rede de transportes p\u00fablicos de sonho. A rede ferrovi\u00e1ria cobre praticamente todas as zonas, \u00e9 segura e pontual, e ainda por cima inventaram uma coisa maravilhosa&nbsp;[ &hellip; ]<\/p>\n","protected":false},"author":2,"featured_media":14587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1283,10,2773,7],"tags":[3135,1582,3145],"_links":{"self":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts\/14586"}],"collection":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/comments?post=14586"}],"version-history":[{"count":0,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts\/14586\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/media\/14587"}],"wp:attachment":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/media?parent=14586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/categories?post=14586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/tags?post=14586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}