{"id":15847,"date":"2013-09-06T13:35:30","date_gmt":"2013-09-06T14:35:30","guid":{"rendered":"http:\/\/www.clubotaku.org\/niji\/?p=15847"},"modified":"2013-09-06T13:35:30","modified_gmt":"2013-09-06T14:35:30","slug":"guia-home-stay-hoteis-residencias-e-aluguer-de-casa","status":"publish","type":"post","link":"https:\/\/www.clubotaku.org\/niji\/socie\/guia-home-stay-hoteis-residencias-e-aluguer-de-casa\/","title":{"rendered":"[Guia] : Home Stay, Hot\u00e9is, Resid\u00eancias e Aluguer de casa"},"content":{"rendered":"<p>Uma estadia prolongada no Jap\u00e3o significa pensar em formas de alojamento que s\u00e3o mais diversificadas do que a solu\u00e7\u00e3o \u201cHotel para Turismo\u201d, e isto \u00e9 uma mais-valia em v\u00e1rios sentidos: ficam a conhecer melhor as condi\u00e7\u00f5es de habita\u00e7\u00e3o no Jap\u00e3o, treinam japon\u00eas, t\u00eam uma experi\u00eancia mais aut\u00eantica e podem mesmo estar mais \u00e0-vontade para fazer coisas como cozinhar em casa, e por fim poupam dinheirinho que tamb\u00e9m \u00e9 muito importante.<\/p>\n<p>Para encontrarem estes espa\u00e7os desapeguem-se de sistemas de &#8220;booking on-line&#8221; em ingl\u00eas, de dicas do <em>tripadvisor<\/em> e de outros modos digitais ocidentais de chegar a saber da exist\u00eancia do alojamento X. Os melhores servi\u00e7os da ind\u00fastria hoteleira japonesa ainda funcionam por clientela sistem\u00e1tica e pela recomenda\u00e7\u00e3o boca-a-boca. Os s\u00edtios melhores e mais acess\u00edveis, isto \u00e9, aqueles em que a rela\u00e7\u00e3o qualidade-pre\u00e7o \u00e9 mais vantajosa, s\u00e3o dif\u00edceis de encontrar por uma simples busca online em motores como o <em>e-dreams<\/em> e afins. O \u00fanico (dos bons) que conseguem reservar pela internet \u2013 mas a partir do Jap\u00e3o \u2013 \u00e9 a cadeia Toyoko-in. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/1688.jpg\" alt=\"1\" width=\"640\" height=\"290\" class=\"aligncenter size-full wp-image-15848\" srcset=\"https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/1688.jpg 640w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/1688-300x135.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Quando v\u00e3o a um Toyoko-in podem fazer um cart\u00e3o de cliente que vos d\u00e1 desconto extra, n\u00e3o pagam nada pelo cart\u00e3o mas t\u00eam de ter uma forma de contacto no Jap\u00e3o \u2013 pode ser uma empresa ou universidade. V\u00e3o-vos tirar uma foto na hora e fazem o cart\u00e3o rapidamente. O atendimento em ingl\u00eas \u00e9 muito limitado ou inexistente mas a p\u00e1gina de internet tem vers\u00e3o em ingl\u00eas. Contudo aconteceu-me o seguinte: n\u00e3o tinham lugar dispon\u00edvel segundo o website mas eu telefonei e eles arranjaram-me lugar.<\/p>\n<p>Esta cadeia de hot\u00e9is tem geralmente os seus estabelecimentos perto das grandes esta\u00e7\u00f5es de transporte, oferece dormidas com pequeno-almo\u00e7o, uso de ar condicionado, TV, yukata\/robe, secador, sabonete e champ\u00f4, com WC e chuveiro privado, tudo por 50 euros por noite (at\u00e9 2 pessoas). As condi\u00e7\u00f5es dos quartos s\u00e3o as de um hotel de 3 estrelas ocidental.<\/p>\n<p>Se a vossa ida para o Jap\u00e3o estiver relacionada com um semestre na Universidade ou um contrato de trabalho tempor\u00e1rio \u00e9 prov\u00e1vel que a Institui\u00e7\u00e3o vos recomende um complexo residencial onde podem alugar um quarto. Notem que v\u00e3o referir \u201capartamento\u201d mas \u00e9 na verdade um T0 que consiste num quarto com bancada de cozinha (mas s\u00f3 bancada), alguns electrodom\u00e9sticos, WC (que pode ter sanita ou n\u00e3o) e s\u00edtio para banho (estilo japon\u00eas). Apesar deste espa\u00e7o provavelmente ser do tamanho da sala de estar da vossa casa (ou menor) \u00e9 na verdade o tipo de s\u00edtio onde as pessoas vivem na cidade quando ainda n\u00e3o t\u00eam filhos nem empregos bem pagos. Se tiver bom isolamento, internet, for num bairro seguro e perto de uma esta\u00e7\u00e3o de transportes digam logo que sim! Existir\u00e3o diversas burocracias a tratar para as quais precisam de ter ao vosso lado uma pessoa n\u00e3o s\u00f3 fluente em japon\u00eas (se voc\u00eas n\u00e3o forem) como tamb\u00e9m conhecedora do sistema de arrendamento tempor\u00e1rio a estrangeiros.<\/p>\n<p>V\u00e3o ter de pagar uma \u201ccortesia\u201d que consiste numa mensalidade extra, que n\u00e3o vos ser\u00e1 devolvida no fim. Esta pr\u00e1tica choca bastante os ocidentais mas consiste na verdade numa \u201cprenda\u201d para o vosso senhorio (e que dispensa que ofere\u00e7am a tal prenda de cortesia que devem dar a todas as pessoas que conhecem formalmente). Notem que o senhorio trata da limpeza e manuten\u00e7\u00e3o do pr\u00e9dio e espa\u00e7o \u00e0 frente da porta, transmite recados das for\u00e7as de seguran\u00e7a, se viver no pr\u00e9dio tamb\u00e9m recebe correio quando n\u00e3o est\u00e3o, bem como recados, e em suma \u00e9 o vosso apoio nesse local. Contudo, n\u00e3o \u00e9 habitual que um estrangeiro alugue casa no Jap\u00e3o a menos que v\u00e1 ficar mais de 6 meses. Por per\u00edodos como um semestre universit\u00e1rio o mais normal \u00e9 colocarem-vos numa resid\u00eancia universit\u00e1ria.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/2484.jpg\" alt=\"2\" width=\"640\" height=\"290\" class=\"aligncenter size-full wp-image-15849\" srcset=\"https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/2484.jpg 640w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/2484-300x135.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>As resid\u00eancias s\u00e3o sempre s\u00edtios onde o ambiente \u00e9 mais jovial, mas n\u00e3o podia ser mais diferente do ambiente de Coimbra ou de outras famosas \u201crep\u00fablicas\u201d. Aqui os quartos s\u00e3o inspeccionados pela Institui\u00e7\u00e3o (nos casos em que vos foi dado) ou, no m\u00ednimo, os vossos colegas (japoneses) n\u00e3o v\u00e3o querer l\u00e1 entrar se n\u00e3o estiver limpo e arrumado. \u00c9 raro que as pessoas partilhem o quarto em si, o espa\u00e7o onde dormem, se n\u00e3o forem fam\u00edlia, por isso em princ\u00edpio n\u00e3o vos v\u00e3o p\u00f4r no quarto com outra pessoa. Existem ainda resid\u00eancias universit\u00e1rias s\u00f3 para raparigas e outras s\u00f3 para rapazes. As das raparigas \u2013 porque n\u00e3o estive nas outras \u2013 t\u00eam seguran\u00e7a \u00e0 porta ou at\u00e9 uma c\u00e2mara de filmar, e voc\u00eas podem mesmo perder o direito de uso se violarem a regra e deixarem entrar rapazes.<\/p>\n<p>Se ficarem num programa de Home Stay \u2013 viver com uma fam\u00edlia japonesa &#8211;  \u00e9 quase certo que vos v\u00e3o p\u00f4r num quarto com cama ocidental. N\u00e3o passa pela cabe\u00e7a dos japoneses que voc\u00eas podem querer dormir num futon (colch\u00e3o no ch\u00e3o de tatami) e as fam\u00edlias que t\u00eam casas com tatami nem se candidatam a estes programas. De qualquer modo, nas cidades as casas n\u00e3o costumam ter tatami excepto numa divis\u00e3o pequenina que s\u00f3 se usa no ver\u00e3o e pelo membro mais velho. O Home Stay \u00e9 uma experi\u00eancia espectacular porque os japoneses em casa s\u00e3o muito descontra\u00eddos, divertidos, ajudam-se muito uns aos outros, e v\u00e3o estar desejosos de vos mostrar redondezas e de fazer comida que torna os jantares em banquetes. Pode ser at\u00e9 demais!<\/p>\n<p>Por isso ofere\u00e7am-se para ajudar, para coisas como lavar a loi\u00e7a, estender roupa, p\u00f4r o lixo na rua, etc. Gestos como ajudar nos trabalhos de casa de ingl\u00eas dos irm\u00e3os mais novos ou ser r\u00e1pido a tomar o duche e o pequeno-almo\u00e7o para n\u00e3o atrasar ningu\u00e9m de manh\u00e3 ir\u00e3o contribuir para a harmonia do lar e todos v\u00e3o ficar a sentir-se bem convosco em casa. Esta ideia de \u201charmonia do lar\u201d \u00e9 muito importante na cultura japonesa. Depois da vossa estadia ser\u00e1 dif\u00edcil separarem-se, viver com uma fam\u00edlia japonesa dilui as dist\u00e2ncias e os afectos criam-se muito rapidamente, por isso se existirem crian\u00e7as n\u00e3o se admirem que chorem. \u00c9 mesmo uma \u201ccoisa que se entranha\u201d mas ser\u00e1 mais f\u00e1cil se trocarem endere\u00e7os de email e de facebook, viva a internet!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/3436.jpg\" alt=\"3\" width=\"640\" height=\"290\" class=\"aligncenter size-full wp-image-15850\" srcset=\"https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/3436.jpg 640w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/3436-300x135.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Por fim, se v\u00e3o passar pelo Jap\u00e3o tirem pelo menos um fim-de-semana para irem a um ryokan, de prefer\u00eancia associado a termas\/onsen. Mas mesmo nas cidades podem existir casas de h\u00f3spedes (guest house) com pequenos apartamentos em estilo de ryokan e que, por n\u00e3o terem a parte das onsen e da gastronomia, s\u00e3o mais acess\u00edveis. Porque \u00e9 que devem ir a um s\u00edtio destes, ou at\u00e9 alugar um quarto tradicional por uma temporada? Porque viver numa divis\u00e3o de tatami, dormir num futon, abrir portas que deslizam, a mesinha lacada ao lado, a yukata vestida, e o ch\u00e1 verde a fumegar \u00e9 uma experi\u00eancia que n\u00e3o v\u00e3o querer perder!<\/p>\n<p>Uma vez estando no Jap\u00e3o perguntem e perguntem que v\u00e3o encontrar s\u00edtios destes nas cidades (excepto Tokyo, Osaka e essas grandes). No campo ent\u00e3o ainda \u00e9 mais f\u00e1cil, e as divis\u00f5es s\u00e3o maiores. Um apartamento para duas pessoas (com 2 set de futon) WC e banho pr\u00f3prio ir\u00e1 custar 800 euros por um m\u00eas (eu fiz isto em Nagasaki) se reservarem com anteced\u00eancia. Este exemplo que vos dou incluiu todos os consumos (\u00e1gua, luz), mudan\u00e7a de toalhas e limpeza di\u00e1ria, ch\u00e1 verde todos os dias, wireless ultra r\u00e1pida, TV, frigor\u00edfico, micro-ondas, e no hall tinha lavandaria, secador e \u00e1gua quente\/fervida.<\/p>\n<p>Seja qual for a vossa escolha, boa estadia!<\/p>\n<p><strong>Escrito por: In\u00eas Carvalho Matos<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma estadia prolongada no Jap\u00e3o significa pensar em formas de alojamento que s\u00e3o mais diversificadas do que a solu\u00e7\u00e3o \u201cHotel para Turismo\u201d, e isto \u00e9 uma mais-valia em v\u00e1rios sentidos:&nbsp;[ &hellip; ]<\/p>\n","protected":false},"author":2,"featured_media":15848,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1283,10,2773,7],"tags":[3367,3366,3368],"_links":{"self":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts\/15847"}],"collection":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/comments?post=15847"}],"version-history":[{"count":0,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts\/15847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/media\/15848"}],"wp:attachment":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/media?parent=15847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/categories?post=15847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/tags?post=15847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}