{"id":17165,"date":"2014-02-25T20:45:23","date_gmt":"2014-02-25T21:45:23","guid":{"rendered":"http:\/\/www.clubotaku.org\/niji\/?p=17165"},"modified":"2014-02-25T20:45:23","modified_gmt":"2014-02-25T21:45:23","slug":"guia-sayonara","status":"publish","type":"post","link":"https:\/\/www.clubotaku.org\/niji\/socie\/guia-sayonara\/","title":{"rendered":"[Guia] : Sayonara"},"content":{"rendered":"<p>Estando no Jap\u00e3o acontecem v\u00e1rias coisas a um ocidental, isto \u00e9, coisas que t\u00eam a ver com a sua adapta\u00e7\u00e3o (ou n\u00e3o), e que o fazem ter consci\u00eancia do que \u00e9 e do que faz de uma maneira que nunca lhe ocorreria se n\u00e3o estivesse no Jap\u00e3o. Este \u00e9 um tema com milhares de entradas em blogues e f\u00f3runs, nas mais diversas l\u00ednguas. <\/p>\n<p>Sendo eu pr\u00f3pria tamb\u00e9m uma dessas pessoas, embora sem a experi\u00eancia de estar no Jap\u00e3o mais de 3 meses seguidos, tenho comunicado com alguns destes bloguers (ali\u00e1s, a comunica\u00e7\u00e3o come\u00e7ou v\u00e1rios meses antes de ir ao Jap\u00e3o desta \u00faltima vez). <\/p>\n<p>Somando as minhas experi\u00eancias \u00e0s deles criei esta lista (altamente subjectiva) de t\u00f3picos, que est\u00e3o numa ordem progressiva &#8211; tanto em ordem cronol\u00f3gica como de intensidade de \u201cimers\u00e3o\u201d. Eventualmente podiam estar aqui outros t\u00f3picos mas estes foram os eleitos. Aceitam-se e agradecem-se partilhas e perguntas da parte dos leitores. <\/p>\n<p>Como hoje \u00e9 exactamente o dia em que, no ano passado, estava a meter-me no avi\u00e3o para regressar, pareceu-me que o devia assinalar desta maneira. Acrescento ainda que este tanto este Guia de Sobreviv\u00eancia como o outro projecto que tive em andamento  &#8211; \u201cUm longo Ver\u00e3o no Jap\u00e3o\u201d &#8211; encerram em 2013. Isto \u00e9, 2012 foi um ano de viagem, 2013 de reflex\u00e3o e produ\u00e7\u00e3o de conte\u00fados sobre essa viagem, e 2014 ser\u00e1&#8230; uma surpresa que ainda n\u00e3o revelo! Mas eu vou estar por aqui, sempre ligada ao Jap\u00e3o. Ja mata ne.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/1823.jpg\" alt=\"1\" width=\"640\" height=\"290\" class=\"aligncenter size-full wp-image-17166\" srcset=\"https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/1823.jpg 640w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/1823-300x135.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><strong>\u201cNo Jap\u00e3o: a lista do que nos acontece quando vamos (para ficar bastante tempo)\u201d<\/strong><\/p>\n<p><strong>1)<\/strong> Em vez de conduzir, usar transportes p\u00fablicos &#8211;> inevit\u00e1vel, pois quando se vai n\u00e3o se leva o carro, mas tamb\u00e9m muito conveniente porque os transportes realmente funcionam. <\/p>\n<p><strong>2)<\/strong> Ter cuidado com a apar\u00eancia ao ponto de redefinir no\u00e7\u00f5es como \u201cparecer bem\u201d e \u201cestar em boa forma\u201d &#8211;> \u00e9 muito mais exigente do que se poderia imaginar, para ambos os sexos e todas as idades sub-60; estar limpo, impec\u00e1vel e \u201cfashion\u201d simplesmente n\u00e3o chega.<\/p>\n<p><strong>3)<\/strong> Ter muito mais cuidado com as boas maneiras, pedindo os \u201cfaz favores e com licen\u00e7as\u201d  todos (e o tempo todo), e de modo geral desacelerar &#8211;> pois s\u00f3 com um permanente cuidado sobre os que nos rodeiam \u00e9 que evitamos maus modos; visto que o ideal n\u00e3o \u00e9 estar sempre a pedir desculpas, \u00e9 evita-las. <\/p>\n<p>04) Ir dormir cedo, e acordar cedo tamb\u00e9m &#8211;> por adapta\u00e7\u00e3o aos ritmos de vida isso acontece logo, mas de modo geral \u00e9 preciso adaptar a dormir menos (8h de sono por noite \u00e9 um conceito alien\u00edgena).<\/p>\n<p><strong>05)<\/strong> Falar ingl\u00eas devagar &#8211;> isto \u00e9 na verdade desaprender ingl\u00eas, pois o (pouco) ingl\u00eas que serve para comunica\u00e7\u00e3o no Jap\u00e3o leva o falante de ingl\u00eas a parecer ridiculamente desprovido de vocabul\u00e1rio e ritmo quando volta a falar com um ingl\u00eas nativo (ao fim de 3 meses pelo menos).<\/p>\n<p><strong>06)<\/strong> Ficar um pouco confuso porque n\u00e3o h\u00e1 assertividade nem capacidade decis\u00f3ria individual, ao ponto de n\u00e3o ser poss\u00edvel saber se um encontro\/evento se vai realizar ou n\u00e3o (porque n\u00e3o dizem que n\u00e3o vai); de modo geral a nega\u00e7\u00e3o n\u00e3o existe.<\/p>\n<p><strong>07)<\/strong> Adoptar certos usos quotidianos tais como por exemplo o uso da toalhinha pequena em volta do pesco\u00e7o (para homens) ou do len\u00e7o de pano que est\u00e1 sempre na mala ou bolso (para mulheres); usar o chap\u00e9u de chuva tamb\u00e9m como chap\u00e9u de sol (em vez ou como suplemento do protector solar).<\/p>\n<p><strong>08)<\/strong> Come\u00e7ar a questionar-se se o protocolo n\u00e3o estar\u00e1 a impedir a efici\u00eancia de certas tarefas simples (isto vai mesmo paracer estranho a quem n\u00e3o tenha estado l\u00e1&#8230; mas quem esteve sabe muito bem o que \u00e9!)<\/p>\n<p><strong>09)<\/strong> Usar a loja de conveni\u00eancia para tudo e mais alguma coisa &#8211;> isto \u00e9 diferente de quando l\u00e1 \u00edamos porque a comida pronta era conveniente ou porque era um bom s\u00edtio para comprar blocos de notas; isto j\u00e1 \u00e9 o n\u00edvel de \u201colha, vou \u00e0 Konbini\u201d quando n\u00e3o temos mais nada que fazer. Existe at\u00e9 um grupo musical japon\u00eas que fez um v\u00eddeoclip sobre isto! <\/p>\n<p><strong>10)<\/strong> Gostar de tomar um banho quente ao final do dia, e concordar absolutamente que esta rotina nos traz qualidade de sono &#8211;> com o tom de nos perguntarmos \u201cmas porque \u00e9 que no Ocidente n\u00e3o fazem isto?\u201d<\/p>\n<p><strong>11)<\/strong> O apartamento pequeno (isto \u00e9, min\u00fasculo) deixou de nos parecer claustrof\u00f3bico e parece agora acolhedor, como o nosso ninho sossegado, e come\u00e7amos a gostar de o arrumar e estar ali a ler ou ver tv, com tudo \u00e0 dist\u00e2ncia de dois passos.<\/p>\n<p><strong>12)<\/strong> Gostar quando um cidad\u00e3os japon\u00eas (geralmente crian\u00e7a ou idoso) mete conversa ou responde a um coment\u00e1rio, por exemplo num supermercado, fila de espera de correios ou  semelhante &#8211;> mas n\u00e3o entender (ainda) que o suposto elogio sobre falarmos bem japon\u00eas \u00e9 na verdade uma cr\u00edtica velada<\/p>\n<p><strong>13)<\/strong> Ir pela primeira vez a um estabelecimento \u201cwestern friendly\u201d (ap\u00f3s mais de 2 meses no Jap\u00e3o geralmente)&#8211;> primeiro com algum sentimento de culpa (\u201cMas ent\u00e3o eu n\u00e3o sou capaz de aguentar estar no Jap\u00e3o?\u201d) e depois com uma sensa\u00e7\u00e3o estranha de estar a desfrutar (\u201cPode-se desfrutar de ser Ocidental?\u201d), e por fim com um efeito cat\u00e1rquico de al\u00edvio (\u201cAh, n\u00e3o sou s\u00f3 eu a notar isso!\u201d) quando metemos conversa com outras pessoas (geralmente americanos, canadianos e australianos).<\/p>\n<p><strong>14)<\/strong> Tornar o consumo de certas coisas t\u00e3o normal que j\u00e1 nem se pensa nisso: o ch\u00e1 verde (mais normal que \u00e1gua), o adamame (feij\u00f5es de soja cozidos em casca), o natto (feij\u00f5es de soja fermentados), o ovo cru na carne grelhada (grelhados em estilo coreano), etc.<\/p>\n<p><strong>15)<\/strong> Dormir no comboio, ou sempre que h\u00e1 um banco livre e 10 minutos desocupados &#8211;> isto s\u00e3o as tais 5 ou 6 horas de sono por dia a matar o ritmo do ocidental habituado \u00e0s 8 horas. <\/p>\n<p><strong>16)<\/strong> (secretamente) Listar coisas irritantes na vida di\u00e1ria no Jap\u00e3o e\/ou na sociedade japonesa, mas apenas para reflectir sobre elas e compreender como as contornar. (\u00f3ptimo motivo de conversa na pr\u00f3xima visita ao bar western friendly, muito terap\u00eautico, porque no fundo todos adoramos o Jap\u00e3o) <\/p>\n<p><strong>17)<\/strong> Manifesta\u00e7\u00e3o de uma certa paix\u00e3o por vending machines &#8211;> misto de utilidade, curiosidade e incapacidade de n\u00e3o ir l\u00e1 ver o que tem para vender.<\/p>\n<p><strong>18)<\/strong> Come\u00e7ar a entender sentimentos complexos tais como a \u201csolid\u00e3o na multid\u00e3o\u201d e o conceito de \u201cface\u201d (cara-fachada) nas rela\u00e7\u00f5es sociais &#8211;> isto j\u00e1 \u00e9 um daqueles territ\u00f3rios de experi\u00eancia emocional equivalente a sentir o \u201cfado\u201d ou a \u201csaudade\u201d para o portugu\u00eas, mas muito levezinho&#8230;<\/p>\n<p><strong>19)<\/strong> Compreender que sempre que nos disseram que fal\u00e1vamos bem japon\u00eas ou us\u00e1vamos bem os pausinhos ou sent\u00e1vamos bem de joelhos estavam na verdade a indicar que n\u00e3o est\u00e1vamos a fazer nenhuma dessas coisas bem; tal como muitos outros coment\u00e1rios sociais significam exactamente o contr\u00e1rio daquilo que soam. <\/p>\n<p><strong>20)<\/strong> Gostar da distribui\u00e7\u00e3o de len\u00e7os de papel (pequenos pacotes com 8 a 10 unidades) na rua, mas (compreender com alguma m\u00e1goa que isso) \u00e9 porque sorriem para n\u00f3s, falam connosco e nos entregam uma coisa m\u00e3o-em-m\u00e3o.<\/p>\n<p><strong>21)<\/strong> Notar que se est\u00e1 numa sociedade fortemente definida por quest\u00f5es de g\u00e9nero (se \u00e9 mulher nota que s\u00f3 tem \u00e0 sua volta outras mulheres; se \u00e9 homem nota que s\u00f3 tem \u00e0 sua volta outros homens; e sobretudo que a situa\u00e7\u00e3o n\u00e3o \u00e9 revers\u00edvel).<\/p>\n<p><strong>22)<\/strong> Adorar as meias dos p\u00e9s com dedos e pensar em comprar v\u00e1rias para trazer para casa; isto geralmente vem acompanhado dos primeiros pensamentos preparat\u00f3rios de voltar para casa, tais como \u201co que vou levar?\u201d e \u201cque postal de obrigado vou dar aos meus amigos\/colegas?\u201d<\/p>\n<p><strong>23)<\/strong> Escrever um blog ou di\u00e1rio e de modo geral querer partilhar com os outros os efeitos de uma estadia prolongada no Jap\u00e3o, com alguma esperan\u00e7a de motivar outras pessoas a viver essa experi\u00eancia e ajudar no (inevit\u00e1vel) impacto (choque?) cultural.<\/p>\n<p><strong>Escrito por: In\u00eas Carvalho Matos<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estando no Jap\u00e3o acontecem v\u00e1rias coisas a um ocidental, isto \u00e9, coisas que t\u00eam a ver com a sua adapta\u00e7\u00e3o (ou n\u00e3o), e que o fazem ter consci\u00eancia do que&nbsp;[ &hellip; ]<\/p>\n","protected":false},"author":2,"featured_media":17166,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1283,10,7],"tags":[3169],"_links":{"self":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts\/17165"}],"collection":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/comments?post=17165"}],"version-history":[{"count":0,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts\/17165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/media\/17166"}],"wp:attachment":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/media?parent=17165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/categories?post=17165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/tags?post=17165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}