{"id":18710,"date":"2014-12-25T19:59:57","date_gmt":"2014-12-25T20:59:57","guid":{"rendered":"http:\/\/www.clubotaku.org\/niji\/?p=18710"},"modified":"2017-03-21T19:13:28","modified_gmt":"2017-03-21T20:13:28","slug":"bis","status":"publish","type":"post","link":"https:\/\/www.clubotaku.org\/niji\/music\/bis\/","title":{"rendered":"BiS"},"content":{"rendered":"<p>Est\u00e1vamos em 2010 quando as BiS (Brand-new Idol Society), irromperam no universo dos \u201cIdols\u201d, o g\u00e9nero musical povoado por rapariguinhas em idade escolar, de vozes estridentes e sentimentos cristalinos, que com os seus guarda-roupas extravagantes e pop multicolorida seduziu o Jap\u00e3o.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-18712\" src=\"http:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/1962.jpg\" alt=\"1\" width=\"640\" height=\"290\" srcset=\"https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/1962.jpg 640w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/1962-300x135.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>O seu manifesto tinha tanto de obstinado como de ambivalente: aniquilar as AKB48 e todas as coisas \u2018giras\u2019 sem abdicar da inten\u00e7\u00e3o de se tornarem, elas pr\u00f3prias, \u00eddolos.<\/p>\n<p>Tal des\u00edgnio enfrentou a desconfian\u00e7a inicial dos fervorosos admiradores dos \u2018Idols\u2019 e a indiferen\u00e7a de todos os restantes mas as meninas tinham uma atitude \u00fanica e as apari\u00e7\u00f5es promocionais, controversas, come\u00e7aram a ter eco um pouco por todo o lado. Mais importante ainda: a m\u00fasica era muito boa.<\/p>\n<p>Ap\u00f3s um \u00e1lbum estreia curioso que canalizava uma postura desafiante atrav\u00e9s de uma mistura agrad\u00e1vel de \u2018power-pop\u2019, puro rock, electro-pop e at\u00e9 \u2018vapourwave\u2019, o ano de 2012 assistiu \u00e0 sua passagem para o selo da respeit\u00e1vel \u201cAvex Trax\u201d e a apresenta\u00e7\u00e3o triunfal da obra-prima \u201cIdol Is Dead\u201d.<\/p>\n<p>Sem paralelo na cena \u2018Idol\u2019 ou em qualquer outro g\u00e9nero musical, as BiS moviam-se, graciosamente, pelo mais cavernoso metal, ritmos hardcore, pop delicodoce, \u2018shoegazing\u2019, m\u00fasica de dan\u00e7a, \u2018piano rockers\u2019 e at\u00e9 uma delicada balada, na forma de \u2018Hitoribochi\u2019.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-18713\" src=\"http:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/2607.jpg\" alt=\"2\" width=\"640\" height=\"290\" srcset=\"https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/2607.jpg 640w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/2607-300x135.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Como se a m\u00fasica n\u00e3o fosse suficientemente confrontativa, tudo vinha embrulhado num conceito de \u2018anti-idol\u2019 ou \u2018alternative-idol\u2019 que inclu\u00eda v\u00eddeos radicalmente inovadores e um sem-n\u00famero de actividades paralelas que iam desde protagonizarem uma longa-metragem at\u00e9 colaborarem, em disco e ao vivo, com os radicais de \u2018noise music\u2019, Hijokaidan, o que confirmava as BiS como um projeto multifacetado e determinado a colidir com as funda\u00e7\u00f5es da m\u00fasica pop e a n\u00e3o deixar pedra sobre pedra sobre a imagem tradicionalmente imaculada e submissa dos grupos de \u00eddolos femininos japoneses.<\/p>\n<p>Obviamente, n\u00e3o poderia durar muito tempo. Pelo menos com o n\u00edvel de intensidade imposto \u00e0s\/pelas meninas.<br \/>\nFinalmente, este ano, ap\u00f3s v\u00e1rias e tumultuosas altera\u00e7\u00f5es na forma\u00e7\u00e3o inicial, da qual apenas restavam a l\u00edder e fundadora Pour Lui e Nozomi Hirano, para al\u00e9m do mentor do projeto,<\/p>\n<p>Watanabe Junnosuke, e da equipa de produ\u00e7\u00e3o musical liderada por Kenta Matsukuma, as BiS anunciaram a sua fun\u00e9rea dissolu\u00e7\u00e3o (literalmente, com direito a templo mortu\u00e1rio e coroas de flores!) com um extravagante concerto de despedida com a dura\u00e7\u00e3o de tr\u00eas horas na imensa Yokohama Arena \u2013 uma ironia para um projeto que construiu a sua aura com infames atua\u00e7\u00f5es em pequenas salas claustrof\u00f3bicas e apinhadas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-18711\" src=\"http:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/3554.jpg\" alt=\"3\" width=\"640\" height=\"290\" srcset=\"https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/3554.jpg 640w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/3554-300x135.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Compilando um trilho de \u2018singles\u2019 fabulosos, (\u2018BiSimulation\u2019, \u2018DiE\u2019, \u2018Fly\u2019, \u2018STUPiG\u2019 e a colabora\u00e7\u00e3o com as colegas de editora Dorothy Little Happy, \u2018Get You\u2019), \u201cWho Killed Idol\u201d \u00e9 uma apote\u00f3tica despedida digna de um projeto \u00fanico e, ainda que n\u00e3o soe t\u00e3o consistentemente brilhante como \u201cIdol Is Dead\u201d (um feito imposs\u00edvel, para este ou qualquer outro grupo), continua a ser uma mistura entusi\u00e1stica de m\u00faltiplos estilos musicais a que junta o \u2018ska\u2019 de \u2018Mura Mura\u2019, com uma forma\u00e7\u00e3o em topo de forma e interpreta\u00e7\u00f5es en\u00e9rgicas.<\/p>\n<p>Lend\u00e1rias, como Pour Lui desejava que fossem recordadas: \u2018Idol is dead, long live BiS\u2019!<\/p>\n<p><strong>Escrito por: Claudio Pedrosa<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1vamos em 2010 quando as BiS (Brand-new Idol Society), irromperam no universo dos \u201cIdols\u201d, o g\u00e9nero musical povoado por rapariguinhas em idade escolar, de vozes estridentes e sentimentos cristalinos, que&nbsp;[ &hellip; ]<\/p>\n","protected":false},"author":2,"featured_media":18712,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1283,9],"tags":[3980,2011,1472,3996],"_links":{"self":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts\/18710"}],"collection":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/comments?post=18710"}],"version-history":[{"count":2,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts\/18710\/revisions"}],"predecessor-version":[{"id":23662,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts\/18710\/revisions\/23662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/media\/18712"}],"wp:attachment":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/media?parent=18710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/categories?post=18710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/tags?post=18710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}