{"id":29589,"date":"2020-06-21T16:41:14","date_gmt":"2020-06-21T17:41:14","guid":{"rendered":"http:\/\/www.clubotaku.org\/niji\/?p=29589"},"modified":"2020-06-21T17:21:30","modified_gmt":"2020-06-21T18:21:30","slug":"at-night-i-become-a-monster","status":"publish","type":"post","link":"https:\/\/www.clubotaku.org\/niji\/cultu\/at-night-i-become-a-monster\/","title":{"rendered":"At Night, I Become a Monster"},"content":{"rendered":"<p>Acaba de ser lan\u00e7ado a light novel \u201cAt Night, I Become a Monster\u201d (\u3088\u308b\u306e\u3070\u3051\u3082\u306e &#8211; Yoru no Bakemono, como t\u00edtulo original do livro), a mais recente obra de Yoru Sumino, autor conhecido por \u201cI Want to Eat Your Pancreas\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/Yoru-no-Bakemono.jpg\" alt=\"\" width=\"1280\" height=\"580\" class=\"aligncenter size-full wp-image-29590\" srcset=\"https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/Yoru-no-Bakemono.jpg 1280w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/Yoru-no-Bakemono-600x272.jpg 600w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/Yoru-no-Bakemono-1024x464.jpg 1024w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/Yoru-no-Bakemono-768x348.jpg 768w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/Yoru-no-Bakemono-710x322.jpg 710w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Este livro conta-nos a hist\u00f3ria de Adachi, um jovem estudante que todas as noites se transforma num monstro feito de escurid\u00e3o, com oito olhos e seis pernas. No decorrer de uma das suas aventuras noturnas, Adachi encontra Yano, a sua colega de turma que \u00e9 v\u00edtima de bullying. Este encontro desencadeia mudan\u00e7as na vida de Adachi, que se v\u00ea obrigado a confrontar a realidade do que acontece durante o dia.<\/p>\n<p>Esta \u00e9 a primeira vez que leio um livro deste autor e devo dizer que fiquei bastante impressionada, sendo que daqui em diante ficarei atenta ao lan\u00e7amento de novas obras. Este \u00e9 um livro que aborda v\u00e1rios temas, como o bullying, a intoler\u00e2ncia, a passividade, a amizade, o sentido de unidade, entre outros. Com uma narrativa centrada na dualidade do dia e da noite, o autor desafia o protagonista e o leitor a prosseguir pelo caminho da introspec\u00e7\u00e3o, levando-nos a questionar as nossas ac\u00e7\u00f5es e a nossa pr\u00f3pria dualidade perante as outras pessoas.<\/p>\n<p>Muitas vezes temos de esconder quem verdadeiramente somos ou sentimos que somos obrigados a fazer algo que acreditamos n\u00e3o estar certo s\u00f3 para sentirmos que fazemos parte de algo maior. Por\u00e9m, n\u00e3o devemos fingir que nada se passa, nem ter atitudes que prejudicam os outros. Uma frase que define muito bem este livro \u00e9: quem v\u00ea caras n\u00e3o v\u00ea cora\u00e7\u00f5es. Perceber e aceitar a diferen\u00e7a que reside em cada um de n\u00f3s \u00e9 crucial para viver em sociedade. \u201cQuem \u00e9 a afinal o verdadeiro monstro?\u201d \u00e9 a pergunta que fica no nosso pensamento.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/YorunoBakemono_LightNovel.jpg\" alt=\"\" width=\"1280\" height=\"1907\" class=\"aligncenter size-full wp-image-29592\" srcset=\"https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/YorunoBakemono_LightNovel.jpg 1280w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/YorunoBakemono_LightNovel-201x300.jpg 201w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/YorunoBakemono_LightNovel-687x1024.jpg 687w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/YorunoBakemono_LightNovel-768x1144.jpg 768w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/YorunoBakemono_LightNovel-1031x1536.jpg 1031w, https:\/\/www.clubotaku.org\/nijiwp\/wp-content\/uploads\/YorunoBakemono_LightNovel-710x1058.jpg 710w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Um dos pontos altos do livro \u00e9 sem d\u00favida Yano, que quase sempre rouba o protagonismo a Adachi. Ele pode ser sobrenatural, mas \u00e9 ela quem se revela ser a personagem mais extraordin\u00e1ria. A sua personalidade peculiar, mesmo que \u00e0s vezes um pouco irritante, comparada com a permanente indecis\u00e3o e transig\u00eancia de Adachi, torna-a mais cativante aos olhos do leitor. <\/p>\n<p>Apenas tenho dois pontos negativos a referir; a natureza um pouco infantil de algumas cenas tendo em conta os temas pesados que aborda e a exist\u00eancia de pontas soltas relativamente a algumas personagens. N\u00e3o sei se alguma vez tal ir\u00e1 acontecer, mas adoraria ler uma sequela em que essas quest\u00f5es fossem finalmente respondidas.<\/p>\n<p>Pela excelente qualidade de edi\u00e7\u00e3o, pela qual a Seven Seas merece felicita\u00e7\u00f5es, e escrita fant\u00e1stica do autor, acredito que esta \u00e9 uma \u00f3ptima escolha para uma futura leitura.<\/p>\n<p><strong>Escrito por: Alexandra Costa Ferreira<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acaba de ser lan\u00e7ado a light novel \u201cAt Night, I Become a Monster\u201d (\u3088\u308b\u306e\u3070\u3051\u3082\u306e &#8211; Yoru no Bakemono, como t\u00edtulo original do livro), a mais recente obra de Yoru Sumino,&nbsp;[ &hellip; ]<\/p>\n","protected":false},"author":2,"featured_media":29590,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1283,10],"tags":[7328,3081,7329,7327],"_links":{"self":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts\/29589"}],"collection":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/comments?post=29589"}],"version-history":[{"count":5,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts\/29589\/revisions"}],"predecessor-version":[{"id":29596,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/posts\/29589\/revisions\/29596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/media\/29590"}],"wp:attachment":[{"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/media?parent=29589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/categories?post=29589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clubotaku.org\/niji\/wp-json\/wp\/v2\/tags?post=29589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}